{"id":28379,"date":"2026-05-14T09:23:07","date_gmt":"2026-05-14T07:23:07","guid":{"rendered":"https:\/\/blogs.sindominio.net\/lacinetika\/?p=28379"},"modified":"2026-05-14T09:23:09","modified_gmt":"2026-05-14T07:23:09","slug":"aixo-es-avui-14-05-26-club-de-lectura-de-novel-la-llegim-antologia-de-relats-narra-karcelona","status":"publish","type":"post","link":"https:\/\/blogs.sindominio.net\/lacinetika\/2026\/05\/14\/aixo-es-avui-14-05-26-club-de-lectura-de-novel-la-llegim-antologia-de-relats-narra-karcelona\/","title":{"rendered":"Aix\u00f2 \u00e9s avui: 14\/05\/26 Club de lectura de novel.la: llegim Antologia de relats Narra Karcelona"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/blogs.sindominio.net\/lacinetika\/files\/2026\/05\/photo_2026-05-13_21-23-14-724x1024.jpg\" alt=\"\" class=\"wp-image-28377\" srcset=\"https:\/\/blogs.sindominio.net\/lacinetika\/files\/2026\/05\/photo_2026-05-13_21-23-14-724x1024.jpg 724w, https:\/\/blogs.sindominio.net\/lacinetika\/files\/2026\/05\/photo_2026-05-13_21-23-14-212x300.jpg 212w, https:\/\/blogs.sindominio.net\/lacinetika\/files\/2026\/05\/photo_2026-05-13_21-23-14-768x1086.jpg 768w, https:\/\/blogs.sindominio.net\/lacinetika\/files\/2026\/05\/photo_2026-05-13_21-23-14.jpg 905w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pel <strong>mes de maig<\/strong> llegirem<strong> l&#8217;Antologia de relats Narra Karcelona<\/strong>, que es va presentar per l&#8217;aniversari de la Cin\u00e8tika!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Club de lectura ser\u00e0 <strong>el dijous 14 de maig a les 17:30h<\/strong>. Pots venir encara que no hagis llegit el llibre!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ens reunirem <strong>el segon dijous de cada mes<\/strong>, portarem llegit un llibre triat el mes anterior, i el comentarem!<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Pel mes de maig llegirem l&#8217;Antologia de relats Narra Karcelona, que es va presentar per l&#8217;aniversari de la Cin\u00e8tika! El Club de lectura ser\u00e0 el dijous 14 de maig a les 17:30h. Pots venir encara que no hagis llegit el llibre! Ens reunirem el segon dijous de cada mes, portarem <a class=\"mh-excerpt-more\" href=\"https:\/\/blogs.sindominio.net\/lacinetika\/2026\/05\/14\/aixo-es-avui-14-05-26-club-de-lectura-de-novel-la-llegim-antologia-de-relats-narra-karcelona\/\" title=\"Aix\u00f2 \u00e9s avui: 14\/05\/26 Club de lectura de novel.la: llegim Antologia de relats Narra Karcelona\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":261,"featured_media":28377,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-28379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projectes"],"jetpack_featured_media_url":"https:\/\/blogs.sindominio.net\/lacinetika\/files\/2026\/05\/photo_2026-05-13_21-23-14.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blogs.sindominio.net\/lacinetika\/wp-json\/wp\/v2\/posts\/28379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.sindominio.net\/lacinetika\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.sindominio.net\/lacinetika\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.sindominio.net\/lacinetika\/wp-json\/wp\/v2\/users\/261"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.sindominio.net\/lacinetika\/wp-json\/wp\/v2\/comments?post=28379"}],"version-history":[{"count":2,"href":"https:\/\/blogs.sindominio.net\/lacinetika\/wp-json\/wp\/v2\/posts\/28379\/revisions"}],"predecessor-version":[{"id":28381,"href":"https:\/\/blogs.sindominio.net\/lacinetika\/wp-json\/wp\/v2\/posts\/28379\/revisions\/28381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.sindominio.net\/lacinetika\/wp-json\/wp\/v2\/media\/28377"}],"wp:attachment":[{"href":"https:\/\/blogs.sindominio.net\/lacinetika\/wp-json\/wp\/v2\/media?parent=28379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.sindominio.net\/lacinetika\/wp-json\/wp\/v2\/categories?post=28379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.sindominio.net\/lacinetika\/wp-json\/wp\/v2\/tags?post=28379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}